{"id":652,"count":1,"description":"","link":"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/","name":"Sabberlack","slug":"sabberlack","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sabberlack Archive -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sabberlack Archive -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/\",\"url\":\"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/\",\"name\":\"Sabberlack Archive -\",\"isPartOf\":{\"@id\":\"https:\/\/wegwerfenwargestern.de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/wegwerfenwargestern.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sabberlack\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wegwerfenwargestern.de\/#website\",\"url\":\"https:\/\/wegwerfenwargestern.de\/\",\"name\":\"Wegwerfen war gestern\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/wegwerfenwargestern.de\/#\/schema\/person\/b1afdd8bdf19d681d1c4e6ade0c90299\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wegwerfenwargestern.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/wegwerfenwargestern.de\/#\/schema\/person\/b1afdd8bdf19d681d1c4e6ade0c90299\",\"name\":\"Elke Jacobs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/wegwerfenwargestern.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/wegwerfenwargestern.de\/wp-content\/uploads\/2017\/09\/Darkanium12345.jpg\",\"contentUrl\":\"https:\/\/wegwerfenwargestern.de\/wp-content\/uploads\/2017\/09\/Darkanium12345.jpg\",\"width\":1956,\"height\":1100,\"caption\":\"Elke Jacobs\"},\"logo\":{\"@id\":\"https:\/\/wegwerfenwargestern.de\/#\/schema\/person\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sabberlack Archive -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/","og_locale":"de_DE","og_type":"article","og_title":"Sabberlack Archive -","og_url":"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/","url":"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/","name":"Sabberlack Archive -","isPartOf":{"@id":"https:\/\/wegwerfenwargestern.de\/#website"},"breadcrumb":{"@id":"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/wegwerfenwargestern.de\/index.php\/tag\/sabberlack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wegwerfenwargestern.de\/"},{"@type":"ListItem","position":2,"name":"Sabberlack"}]},{"@type":"WebSite","@id":"https:\/\/wegwerfenwargestern.de\/#website","url":"https:\/\/wegwerfenwargestern.de\/","name":"Wegwerfen war gestern","description":"","publisher":{"@id":"https:\/\/wegwerfenwargestern.de\/#\/schema\/person\/b1afdd8bdf19d681d1c4e6ade0c90299"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wegwerfenwargestern.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wegwerfenwargestern.de\/#\/schema\/person\/b1afdd8bdf19d681d1c4e6ade0c90299","name":"Elke Jacobs","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wegwerfenwargestern.de\/#\/schema\/person\/image\/","url":"https:\/\/wegwerfenwargestern.de\/wp-content\/uploads\/2017\/09\/Darkanium12345.jpg","contentUrl":"https:\/\/wegwerfenwargestern.de\/wp-content\/uploads\/2017\/09\/Darkanium12345.jpg","width":1956,"height":1100,"caption":"Elke Jacobs"},"logo":{"@id":"https:\/\/wegwerfenwargestern.de\/#\/schema\/person\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wegwerfenwargestern.de\/index.php\/wp-json\/wp\/v2\/tags\/652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wegwerfenwargestern.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wegwerfenwargestern.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wegwerfenwargestern.de\/index.php\/wp-json\/wp\/v2\/posts?tags=652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}